{"id":19440,"date":"2026-02-04T22:40:03","date_gmt":"2026-02-04T22:40:03","guid":{"rendered":"https:\/\/geacademy.org\/new\/?page_id=19440"},"modified":"2026-02-07T15:35:53","modified_gmt":"2026-02-07T15:35:53","slug":"admissions","status":"publish","type":"page","link":"https:\/\/geacademy.org\/new\/admissions\/","title":{"rendered":"Admissions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19440\" class=\"elementor elementor-19440\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-8d712a1 e-flex e-con-boxed e-con e-parent\" data-id=\"8d712a1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-2d25707 elementor-widget elementor-widget-heading\" data-id=\"2d25707\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Admissions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-b100b8f e-flex e-con-boxed e-con e-parent\" data-id=\"b100b8f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-e3a8484 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-rs-heading\" data-id=\"e3a8484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        <div class=\"prelements-heading style1 center  animate-  \">\r\n            <div class=\"title-inner\">\r\n\t\t\t\t                    <span class=\"sub-text \">\r\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Enrollment\t\t\t\t\t<\/span>\r\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"0.8\" data-delay=\"0.06\">Age Requirements<\/h2>            <\/div>\r\n\t\t\t                <div class=\"descripti\">\r\n\t\t\t\t\t<p>Students entering Pre-School, Pre-K, and Kindergarten must meet the following age requirements.<\/p>                <\/div>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-6d3c9a0 e-flex e-con-boxed e-con e-parent\" data-id=\"6d3c9a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-d5de141 e-con-full e-flex e-con e-child\" data-id=\"d5de141\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-2d7f4e9 e-con-full e-flex e-con e-child\" data-id=\"2d7f4e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-6edc312 elementor-widget elementor-widget-heading\" data-id=\"6edc312\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 years<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-26c7fe3 elementor-widget elementor-widget-heading\" data-id=\"26c7fe3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pre-School<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-1d5f00b elementor-widget elementor-widget-heading\" data-id=\"1d5f00b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">On or before September 1st<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-de1e16d e-con-full e-flex e-con e-child\" data-id=\"de1e16d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-0f7e48e elementor-widget elementor-widget-heading\" data-id=\"0f7e48e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4 years<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-97f0888 elementor-widget elementor-widget-heading\" data-id=\"97f0888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pre-Kindergarten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-3d2ce54 elementor-widget elementor-widget-heading\" data-id=\"3d2ce54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">On or before September 1st<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-af332c2 e-con-full e-flex e-con e-child\" data-id=\"af332c2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-72ec151 elementor-widget elementor-widget-heading\" data-id=\"72ec151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5 years<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-b304dcd elementor-widget elementor-widget-heading\" data-id=\"b304dcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kindergarten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-10913ba elementor-widget elementor-widget-heading\" data-id=\"10913ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">On or before September 1st<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-1da574c elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-rs-heading\" data-id=\"1da574c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        <div class=\"prelements-heading style1 left  animate-  \">\r\n            <div class=\"title-inner\">\r\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"0.8\" data-delay=\"0.06\">Required Documents<\/h2>            <\/div>\r\n\t\t\t                <div class=\"descripti\">\r\n\t\t\t\t\t<p>All applicants are required to provide the following documents. No student may attend class without these documents.<\/p>                <\/div>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-10ee8eb elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"10ee8eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Completed Registration Forms &amp; Fees<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-eeeab4c elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"eeeab4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Copy of Birth Certificate<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-fa4fd13 elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"fa4fd13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Social Security Number<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-754b740 elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"754b740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Health Form<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-d722655 elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"d722655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Allergy Form<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-6033961 elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"6033961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Eye Examination Form<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-c3c0313 elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"c3c0313\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Dental Examination Form<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-c520f05 elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"c520f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Signed Parent Agreement<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-895279e elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"895279e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">Take Entrance Test<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-19c7469 elementor-widget__width-initial elementor-widget elementor-widget-rs-iconbox\" data-id=\"19c7469\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-iconbox-area\">\r\n\t\t\t                <a class=\"box-inner \" href=\"#\" >\r\n\t\t\t\t\t            <div class=\"icon-area\">\r\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>            <\/div>\r\n\t\t        <div class=\"text-area\">\r\n\t\t\t<h5 class=\"title\">All previous Report Cards (if applicable)<\/h5>        <\/div>\r\n\t\t                <\/a>\r\n\t\t\t        <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-8f1fa51 e-flex e-con-boxed e-con e-parent\" data-id=\"8f1fa51\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-75eb5a7 e-con-full e-flex e-con e-child\" data-id=\"75eb5a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-c75eded elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c75eded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-exclamation-triangle\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M569.517 440.013C587.975 472.007 564.806 512 527.94 512H48.054c-36.937 0-59.999-40.055-41.577-71.987L246.423 23.985c18.467-32.009 64.72-31.951 83.154 0l239.94 416.028zM288 354c-25.405 0-46 20.595-46 46s20.595 46 46 46 46-20.595 46-46-20.595-46-46-46zm-43.673-165.346l7.418 136c.347 6.364 5.609 11.346 11.982 11.346h48.546c6.373 0 11.635-4.982 11.982-11.346l7.418-136c.375-6.874-5.098-12.654-11.982-12.654h-63.383c-6.884 0-12.356 5.78-11.981 12.654z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Important Notes for Pre-School and Pre-K<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-fd37bb8 elementor-widget elementor-widget-heading\" data-id=\"fd37bb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our mission is to guide young children to develop a true and strong character and a lifelong love for learning. We intend to work closely with the family and the community to produce responsible and successful citizens.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-479ec8b e-con-full e-flex e-con e-child\" data-id=\"479ec8b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-573858d elementor-widget elementor-widget-heading\" data-id=\"573858d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ready to Apply?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-0c5d1e3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0c5d1e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Begin your child's journey at GEA today. Complete our online application form to start the enrollment process.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-aos-once=\"true\" class=\"elementor-element elementor-element-176f008 elementor-widget elementor-widget-rs-button\" data-id=\"176f008\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <a class=\"rs-button style-default icon-anim-none text-anim-none\" href=\"\/apply-now\/\">\r\n\t\t\t                <span class=\"button-icon\">\r\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>                <\/span>\r\n\t\t\t\t\t\t                <span class=\"button-text\">\r\n                    Request Admission                <\/span>\r\n\t\t\t        <\/a>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Admissions Enrollment Age Requirements Students entering Pre-School, Pre-K, and Kindergarten must meet the following age requirements. 3 years Pre-School On or before September 1st 4 years Pre-Kindergarten On or before September 1st 5 years Kindergarten On or before September 1st Required Documents All applicants are required to provide the following documents. No student may attend [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-19440","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/pages\/19440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/comments?post=19440"}],"version-history":[{"count":28,"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/pages\/19440\/revisions"}],"predecessor-version":[{"id":20223,"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/pages\/19440\/revisions\/20223"}],"wp:attachment":[{"href":"https:\/\/geacademy.org\/new\/wp-json\/wp\/v2\/media?parent=19440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}